{"id":11987,"date":"2025-04-24T09:48:08","date_gmt":"2025-04-24T07:48:08","guid":{"rendered":"https:\/\/www.purpan.fr\/?p=11987"},"modified":"2025-04-24T09:48:12","modified_gmt":"2025-04-24T07:48:12","slug":"des-coleopteres-inedits-et-un-hommage-a-un-enseignant-chercheur-de-purpan","status":"publish","type":"post","link":"https:\/\/www.purpan.fr\/en\/2025\/04\/24\/des-coleopteres-inedits-et-un-hommage-a-un-enseignant-chercheur-de-purpan\/","title":{"rendered":"Des col\u00e9opt\u00e8res in\u00e9dits\u2026 et un hommage \u00e0 un enseignant-chercheur de PURPAN !"},"content":{"rendered":"\n<p>Lors d\u2019une mission scientifique en Guyane en 2024 organis\u00e9e par le Museum National d\u2019Histoire Naturelle, plusieurs nouvelles esp\u00e8ces d\u2019insectes ont \u00e9t\u00e9 d\u00e9couvertes par une \u00e9quipe de sp\u00e9cialistes, dont <a href=\"https:\/\/www.linkedin.com\/in\/ACoAACXcD2QBC6zGnKcTWzW0NIgmcW9C7mRbALo\"><\/a><a href=\"https:\/\/www.linkedin.com\/in\/herv%C3%A9-brustel-430878158\/\">Herv\u00e9 Brustel<\/a>, enseignant-chercheur en entomologie \u00e0 l\u2019<a href=\"https:\/\/www.linkedin.com\/company\/ecole-d-ingenieurs-de-purpan\/\">Ecole d&#8217;Ing\u00e9nieurs de PURPAN<\/a>.<br><br>Parmi ces d\u00e9couvertes, l\u2019esp\u00e8ce <em>Hybalus brusteli<\/em> a \u00e9t\u00e9 nomm\u00e9e en son honneur, saluant son expertise en entomologie foresti\u00e8re et sa participation active \u00e0 cette mission de terrain.<br><br>Cette reconnaissance illustre l\u2019implication de nos enseignantes-chercheuses et enseignants-chercheurs dans la recherche internationale, la connaissance et la pr\u00e9servation de la biodiversit\u00e9.<br>Un grand bravo \u00e0 tous les naturalistes de terrain qui d\u00e9ploient tant d\u2019effort pour connaitre et faire connaitre le vivant<br><br>D\u00e9couvrez l\u2019article complet de Thierry DEUVE &#8211; Col\u00e9opt\u00e8res <a href=\"https:\/\/www.purpan.fr\/wp-content\/uploads\/2025\/04\/Coleopteres31.pdf\">sur ce lien.<\/a><br>Retrouvez sur les liens ci-dessous trois publications r\u00e9centes, dont Herv\u00e9 Brustel est co-auteur\u00a0:<br>&#8211; https:\/\/www.mdpi.com\/2075-4450\/16\/4\/411\/<br>&#8211; https:\/\/www.purpan.fr\/wp-content\/uploads\/2025\/04\/Lentomologiste_0425.pdf\/<br>&#8211; https:\/\/www.purpan.fr\/wp-content\/uploads\/2025\/04\/2025-Pyreneotrechus.pdf\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lors d\u2019une mission scientifique en Guyane en 2024 organis\u00e9e par le Museum National d\u2019Histoire Naturelle, plusieurs nouvelles esp\u00e8ces d\u2019insectes ont \u00e9t\u00e9 d\u00e9couvertes par une \u00e9quipe de sp\u00e9cialistes, dont Herv\u00e9 Brustel, enseignant-chercheur en entomologie \u00e0 l\u2019Ecole d&#8217;Ing\u00e9nieurs de PURPAN. Parmi ces d\u00e9couvertes, l\u2019esp\u00e8ce Hybalus brusteli a \u00e9t\u00e9 nomm\u00e9e en son honneur, saluant son expertise en entomologie [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":11990,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-11987","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cat-recherche"],"_links":{"self":[{"href":"https:\/\/www.purpan.fr\/en\/wp-json\/wp\/v2\/posts\/11987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.purpan.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.purpan.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.purpan.fr\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.purpan.fr\/en\/wp-json\/wp\/v2\/comments?post=11987"}],"version-history":[{"count":1,"href":"https:\/\/www.purpan.fr\/en\/wp-json\/wp\/v2\/posts\/11987\/revisions"}],"predecessor-version":[{"id":11992,"href":"https:\/\/www.purpan.fr\/en\/wp-json\/wp\/v2\/posts\/11987\/revisions\/11992"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.purpan.fr\/en\/wp-json\/wp\/v2\/media\/11990"}],"wp:attachment":[{"href":"https:\/\/www.purpan.fr\/en\/wp-json\/wp\/v2\/media?parent=11987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.purpan.fr\/en\/wp-json\/wp\/v2\/categories?post=11987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.purpan.fr\/en\/wp-json\/wp\/v2\/tags?post=11987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}